{"id":4071,"date":"2021-10-14T10:29:38","date_gmt":"2021-10-14T13:29:38","guid":{"rendered":"https:\/\/www.rastrearobjetos.com.br\/blog\/?p=4071"},"modified":"2021-10-14T10:29:38","modified_gmt":"2021-10-14T13:29:38","slug":"correios-apresenta-solucoes-para-exportacao-no-enaex-2021","status":"publish","type":"post","link":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html","title":{"rendered":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021"},"content":{"rendered":"<p>Os Correios, patrocinadores do <a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/enaex\" title=\"Enaex\">Enaex<\/a>, participam com um estande virtual de divulga\u00e7\u00e3o dos produtos e servi\u00e7os do portf\u00f3lio de exporta\u00e7\u00e3o, ressaltando a import\u00e2ncia da empresa no contexto global diante das enormes transforma\u00e7\u00f5es desencadeadas pelo avan\u00e7o do e-commerce. Nesta quinta-feira (14), \u00e0s 15h, os Correios oferecem um workshop sobre o tema \u201c<strong><a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/exporta-facil\" title=\"Exporta F\u00e1cil\">Exporta F\u00e1cil<\/a><\/strong> \u2013 <em>Impulsionando o Com\u00e9rcio Exterior<\/em>\u201d, com a participa\u00e7\u00e3o da consultora em com\u00e9rcio exterior Ana Paula Macri. Para apresentar as solu\u00e7\u00f5es dos Correios que facilitam a exporta\u00e7\u00e3o, o gerente de Portf\u00f3lio de Servi\u00e7os Internacionais dos Correios, Humberto Brito, participar\u00e1 do Painel \u201c<strong>Log\u00edstica no Com\u00e9rcio Exterior Brasileiro<\/strong>\u201d, na sexta-feira (15), \u00e0s 9h.<\/p>\n<p>O <a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/enaex\" title=\"Enaex\">Enaex<\/a> \u2013 Promovido pela <strong>Associa\u00e7\u00e3o de Com\u00e9rcio Exterior do Brasil<\/strong> (<strong><a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/aeb\" title=\"AEB\">AEB<\/a><\/strong>), com apoio dos Correios, o <a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/enaex\" title=\"Enaex\">Enaex<\/a> \u00e9 considerado o mais importante f\u00f3rum brasileiro de com\u00e9rcio exterior. O evento re\u00fane governo e representantes de toda a cadeia de neg\u00f3cios do com\u00e9rcio internacional em palestras, debates, pain\u00e9is e mesas-redondas sobre os principais temas da atualidade. O objetivo \u00e9 discutir, analisar e criar proposi\u00e7\u00f5es que levem \u00e0 expans\u00e3o competitiva e sustent\u00e1vel do setor.<\/p>\n<p>Dada a natureza do evento, o perfil do p\u00fablico \u00e9 de empres\u00e1rios e executivos que est\u00e3o em busca de melhores solu\u00e7\u00f5es para exporta\u00e7\u00e3o de seus produtos e a expans\u00e3o dos seus neg\u00f3cios.<\/p>\n<p>O evento \u00e9 aberto ao p\u00fablico e gratuito. Mais informa\u00e7\u00f5es e a inscri\u00e7\u00e3o est\u00e3o dispon\u00edveis no site do <a href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/tags\/enaex\" title=\"Enaex\">Enaex<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta e sexta-feira, 14 e 15 de outubro, acontece o 40\u00ba Encontro Nacional de Com\u00e9rcio Exterior, Enaex 2021, o maior evento sobre o tema no Brasil. A edi\u00e7\u00e3o ser\u00e1 totalmente online e traz o mote \u201cReformar pra crescer\u201d, com palestras, debates e workshops apresentados por autoridades p\u00fablicas e especialistas em com\u00e9rcio internacional.<\/p>\n","protected":false},"author":1,"featured_media":4072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,11,25],"tags":[2128,2130,2127,2129,524],"class_list":["post-4071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-correios","category-informacoes","category-noticias","tag-2128","tag-aeb","tag-enaex","tag-exporta-facil","tag-logistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios<\/title>\n<meta name=\"description\" content=\"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios\" \/>\n<meta property=\"og:description\" content=\"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\" \/>\n<meta property=\"og:site_name\" content=\"Rastrear Correios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RastreadorDeObjetos\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T13:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1205\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rastreador de Objetos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rastrearobjetos\" \/>\n<meta name=\"twitter:site\" content=\"@rastrearobjetos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rastreador de Objetos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\"},\"author\":{\"name\":\"Rastreador de Objetos\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/0ecfd4bb0e3d1a11c9de7b048f0beaaf\"},\"headline\":\"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021\",\"datePublished\":\"2021-10-14T13:29:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/245619904_3133396500222978_649641380753042705_n.jpg\",\"keywords\":[\"2021\",\"AEB\",\"Enaex\",\"Exporta F\u00e1cil\",\"logistica\"],\"articleSection\":[\"Correios\",\"Informa\u00e7\u00f5es\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\",\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\",\"name\":\"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/245619904_3133396500222978_649641380753042705_n.jpg\",\"datePublished\":\"2021-10-14T13:29:38+00:00\",\"description\":\"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage\",\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/245619904_3133396500222978_649641380753042705_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/245619904_3133396500222978_649641380753042705_n.jpg\",\"width\":1205,\"height\":631,\"caption\":\"Com a palavra na solenidade de abertura, Sr. Jos\u00e9 Augusto de Castro, Presidente Executivo da Associa\u00e7\u00e3o de Com\u00e9rcio Exterior do Brasil \u2013 AEB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/noticias\\\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/categoria\\\/noticias\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/\",\"name\":\"Rastrear Correios\",\"description\":\"Blog do Rastreador dos Correios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#organization\",\"name\":\"Rastrear Objetos dos Correios\",\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logo-correios-1.png\",\"contentUrl\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logo-correios-1.png\",\"width\":314,\"height\":49,\"caption\":\"Rastrear Objetos dos Correios\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RastreadorDeObjetos\",\"https:\\\/\\\/x.com\\\/rastrearobjetos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/0ecfd4bb0e3d1a11c9de7b048f0beaaf\",\"name\":\"Rastreador de Objetos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g\",\"caption\":\"Rastreador de Objetos\"},\"url\":\"https:\\\/\\\/www.rastrearobjetos.com.br\\\/blog\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios","description":"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html","og_locale":"pt_BR","og_type":"article","og_title":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios","og_description":"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.","og_url":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html","og_site_name":"Rastrear Correios","article_publisher":"https:\/\/www.facebook.com\/RastreadorDeObjetos","article_published_time":"2021-10-14T13:29:38+00:00","og_image":[{"width":1205,"height":631,"url":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg","type":"image\/jpeg"}],"author":"Rastreador de Objetos","twitter_card":"summary_large_image","twitter_creator":"@rastrearobjetos","twitter_site":"@rastrearobjetos","twitter_misc":{"Escrito por":"Rastreador de Objetos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#article","isPartOf":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html"},"author":{"name":"Rastreador de Objetos","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#\/schema\/person\/0ecfd4bb0e3d1a11c9de7b048f0beaaf"},"headline":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021","datePublished":"2021-10-14T13:29:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html"},"wordCount":265,"publisher":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg","keywords":["2021","AEB","Enaex","Exporta F\u00e1cil","logistica"],"articleSection":["Correios","Informa\u00e7\u00f5es","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html","url":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html","name":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021 - Rastrear Correios","isPartOf":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage"},"image":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage"},"thumbnailUrl":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg","datePublished":"2021-10-14T13:29:38+00:00","description":"Rastrear Objetos Correios. Rastreamento de sua Encomenda. Acompanhe todos os passos da sua entrega. R\u00e1pido, F\u00e1cil e Gr\u00e1tis. Receba notifica\u00e7\u00f5es atualizadas.","breadcrumb":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#primaryimage","url":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg","contentUrl":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2021\/10\/245619904_3133396500222978_649641380753042705_n.jpg","width":1205,"height":631,"caption":"Com a palavra na solenidade de abertura, Sr. Jos\u00e9 Augusto de Castro, Presidente Executivo da Associa\u00e7\u00e3o de Com\u00e9rcio Exterior do Brasil \u2013 AEB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/noticias\/correios-apresenta-solucoes-para-exportacao-no-enaex-2021.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.rastrearobjetos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.rastrearobjetos.com.br\/blog\/categoria\/noticias"},{"@type":"ListItem","position":3,"name":"Correios apresenta solu\u00e7\u00f5es para exporta\u00e7\u00e3o no Enaex 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#website","url":"https:\/\/www.rastrearobjetos.com.br\/blog\/","name":"Rastrear Correios","description":"Blog do Rastreador dos Correios","publisher":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rastrearobjetos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#organization","name":"Rastrear Objetos dos Correios","url":"https:\/\/www.rastrearobjetos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2017\/09\/logo-correios-1.png","contentUrl":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-content\/uploads\/2017\/09\/logo-correios-1.png","width":314,"height":49,"caption":"Rastrear Objetos dos Correios"},"image":{"@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RastreadorDeObjetos","https:\/\/x.com\/rastrearobjetos"]},{"@type":"Person","@id":"https:\/\/www.rastrearobjetos.com.br\/blog\/#\/schema\/person\/0ecfd4bb0e3d1a11c9de7b048f0beaaf","name":"Rastreador de Objetos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87a6c926c997a0a931c9a06b1dc5dea49d1b1b8fcaf6f0acef031004169a5d76?s=96&d=mm&r=g","caption":"Rastreador de Objetos"},"url":"https:\/\/www.rastrearobjetos.com.br\/blog\/author\/admin"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4071"}],"version-history":[{"count":1,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4071\/revisions"}],"predecessor-version":[{"id":4073,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/posts\/4071\/revisions\/4073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/media\/4072"}],"wp:attachment":[{"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rastrearobjetos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}